{"id":1622,"date":"2015-09-14T08:34:39","date_gmt":"2015-09-14T07:34:39","guid":{"rendered":"https:\/\/www.estateone.biz\/blog\/?p=1622"},"modified":"2015-09-14T08:53:53","modified_gmt":"2015-09-14T07:53:53","slug":"el-paseo-de-la-castellana-antiguamente","status":"publish","type":"post","link":"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/","title":{"rendered":"El Paseo de la Castellana antiguamente"},"content":{"rendered":"<p>S\u00edmbolo del <strong>progreso y la modernidad<\/strong>, eje indiscutible de la <strong>zona financiera<\/strong> de la ciudad, el <strong>Paseo de la Castellana<\/strong> es una de las <strong>avenidas m\u00e1s importantes<\/strong> de Madrid. Rascacielos, oficinas, centros comerciales, bancos, edificios modernos: todos los encontramos a lo largo del <strong>Paseo de la Castellana<\/strong>, una arteria de m\u00e1s de seis kil\u00f3metros de longitud que en pleno siglo XXI define la <strong>zona ejecutiva madrile\u00f1a<\/strong>. Pero esta importante calle ha cambiado much\u00edsimo a lo largo de los a\u00f1os. Dando un paseo por ella nadie pensar\u00eda que antes all\u00ed hab\u00eda una zona de pastoreo con <strong>huertos, descampados, cultivos o arroyos<\/strong>. En el blog de Estate One <a href=\"https:\/\/www.estateone.biz\/blog\/recuerdos-de-la-gran-via\/\">despu\u00e9s de haber recordado c\u00f3mo era la Gran V\u00eda<\/a> volvemos a dar <strong>Un Paseo por el Pasado<\/strong>, esta vez para saber c\u00f3mo era el <strong>Paseo de la Castellana<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/01-caste1.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1635\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/01-caste1.jpg\" alt=\"01-caste\" width=\"648\" height=\"744\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/01-caste1.jpg 648w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/01-caste1-261x300.jpg 261w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/01-caste1-435x500.jpg 435w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/a><\/p>\n<p><strong>DIVIDIENDO LA CIUDAD EN TRES<\/strong><\/p>\n<p>En 1860 la ciudad de Madrid se divide en <strong>tres zonas diferenciadas<\/strong>: casco antiguo, ensanche y extrarradio, y <strong>el Paseo de la Castellana se construye para unir esas tres zonas<\/strong> y atravesar Madrid de norte a sur.<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/03-caste1.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1633\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/03-caste1.jpg\" alt=\"Paseo de la Castellana\" width=\"650\" height=\"614\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/03-caste1.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/03-caste1-300x283.jpg 300w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/03-caste1-529x500.jpg 529w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>En un principio la avenida se llam\u00f3 Paseo de las Delicias de la Princesa y su nacimiento tuvo origen a finales del S. XIX debido a la pujanza de la <strong>aristocracia financiera<\/strong>. \u00c9sta resid\u00eda en el <strong>extrarradio de la ciudad<\/strong>, muy lejos del centro urbano: all\u00ed es donde comienza a construirse la gran avenida, paralela a <strong>casas nobles y palacios<\/strong>. Muchos de esos palacios dispon\u00edan de zonas traseras con cuadras y caballerizas; hoy en d\u00eda est\u00e1n reconvertidos en organismos oficiales y financieros. Para ser conscientes de lo que ha cambiado Madrid desde entonces basta pensar que el Paseo de la Castellana discurr\u00eda por las afueras de la ciudad.<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/02-caste.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1637\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/02-caste.jpg\" alt=\"Paseo de la Castellana\" width=\"650\" height=\"497\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/02-caste.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/02-caste-300x229.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p><strong>DE HIP\u00d3DROMO DE CARRERAS A NUEVOS MINISTERIOS<\/strong><\/p>\n<p>Debido a la creciente afici\u00f3n de la burgues\u00eda madrile\u00f1a por las <strong>carreras de caballos<\/strong> en 1878 se construye el <strong>Hip\u00f3dromo de la Castellana<\/strong>. All\u00ed se daba cita la clase m\u00e1s pudiente de Madrid, mostrando en sociedad sus mejores galas.<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/05-caste.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1639\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/05-caste.jpg\" alt=\"Paseo de la Castellana\" width=\"650\" height=\"430\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/05-caste.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/05-caste-300x198.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>En 1933 se derriba el hip\u00f3dromo para <strong>ampliar el Paseo de la Castellana hacia el norte<\/strong> y se construye un <strong>complejo para las dependencias ministeriales<\/strong> con un <strong>enlace ferroviario subterr\u00e1neo<\/strong>. Es lo que hoy conocemos como <strong>Nuevos Ministerios<\/strong>, la estaci\u00f3n m\u00e1s moderna de Madrid hasta la fecha. Su construcci\u00f3n tuvo que pararse con la Guerra Civil y fue terminada en 1942.<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/04-caste1.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1643\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/04-caste1.jpg\" alt=\"Paseo de la Castellana\" width=\"650\" height=\"911\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/04-caste1.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/04-caste1-214x300.jpg 214w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/04-caste1-356x500.jpg 356w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>Esto marc\u00f3 un <strong>punto de inflexi\u00f3n para la ciudad<\/strong>, pues desde entonces la Castellana sigui\u00f3 prolong\u00e1ndose hacia el norte y Madrid continu\u00f3 creciendo en torno a la gran avenida. En ella se destina <strong>una zona comercial<\/strong> (AZCA y Palacio de Congresos), otra <strong>zona con viviendas<\/strong>, y una tercera zona para <strong>la iniciativa privada<\/strong>. En medio se construye el estadio Santiago Bernabeu (que tuvo tres ampliaciones, pues se quedaba peque\u00f1o para dar cabida a la demanda de aficionados que segu\u00edan el f\u00fatbol).<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/06-caste.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1647\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/06-caste.jpg\" alt=\"Paseo de la Castellana\" width=\"650\" height=\"461\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/06-caste.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/06-caste-300x212.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>AZCA fue inspirado por el Rockefeller Center de Nueva York y su primer edificio fue el del Corte Ingl\u00e9s. Hoy en d\u00eda cuesta creer que <strong>la zona de AZCA estuviera destinada anta\u00f1o al pastoreo y las maniobras militares<\/strong>, pero as\u00ed era. El tercer tramo de la Castellana llega hasta <strong>Plaza de Castilla<\/strong>, que era el lugar donde <strong>los tranv\u00edas daban la vuelta<\/strong>, pues all\u00ed terminaba la ciudad.<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/07-caste.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1645\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/07-caste.jpg\" alt=\"Paseo de la Castellana\" width=\"650\" height=\"375\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/07-caste.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/07-caste-300x173.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>Fue en los a\u00f1os 70 cuando se construyeron los primeros rascacielos de la zona. Actualmente el Paseo de la Castellana tiene seis carriles centrales y cuatro laterales, m\u00e1s de 100 edificios de oficinas y 285.000 personas la recorren cada d\u00eda.<\/p>\n<p><a href=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/08-caste.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1649\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/08-caste.jpg\" alt=\"Paseo de la Castellana\" width=\"650\" height=\"341\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/08-caste.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/08-caste-300x157.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p><strong>UN HOTEL CON MUCHO GLAMOUR<\/strong><\/p>\n<p>En el n\u00famero 2 de la Castellana se encuentra el <strong>hotel Gran Meli\u00e1 F\u00e9nix<\/strong>. Inaugurado en 1953, fue el <strong>preferido de grandes estrellas<\/strong> de cine como Rita Hayworth, Cary Grant o Gloria Swanson, y en 1965 se alojaron en \u00e9l los Beatles.<\/p>\n<p><strong>Fotograf\u00edas 01, 02 y 03:<\/strong> <a href=\"http:\/\/www.madridantiguo.org\" target=\"_blank\">Madrid Antiguo <\/a><\/p>\n<p><strong>Fotograf\u00edas 04, 05 y 06:<\/strong> <a href=\"https:\/\/urbancidades.wordpress.com\" target=\"_blank\">Urbanicidades <\/a><\/p>\n<p><strong>Fotograf\u00eda 07:<\/strong> Telemadrid<\/p>\n<p><strong>Fotograf\u00eda 08: <\/strong><a href=\"https:\/\/www.flickr.com\/photos\/alvy\/\" target=\"_blank\">\u00c1lvaro Ib\u00e1\u00f1ez<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00edmbolo del progreso y la modernidad, eje indiscutible de la zona financiera de la ciudad, el Paseo de la Castellana es una de las avenidas m\u00e1s importantes de Madrid. Rascacielos, oficinas, centros comerciales, bancos, edificios modernos: todos los encontramos a lo largo del Paseo de la Castellana, una arteria de m\u00e1s de seis kil\u00f3metros de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[98],"tags":[26,284,324,325,326],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Paseo de la Castellana antiguamente - Blog, dulce blog<\/title>\n<meta name=\"description\" content=\"S\u00edmbolo del progreso y la modernidad, eje indiscutible de la zona financiera de la ciudad, el Paseo de la Castellana es una de las avenidas m\u00e1s importantes de Madrid.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Paseo de la Castellana antiguamente - Blog, dulce blog\" \/>\n<meta property=\"og:description\" content=\"S\u00edmbolo del progreso y la modernidad, eje indiscutible de la zona financiera de la ciudad, el Paseo de la Castellana es una de las avenidas m\u00e1s importantes de Madrid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog, dulce blog\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-14T07:34:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-14T07:53:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/00-caste.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Estate One\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estate One\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/\",\"url\":\"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/\",\"name\":\"El Paseo de la Castellana antiguamente - Blog, dulce blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website\"},\"datePublished\":\"2015-09-14T07:34:39+00:00\",\"dateModified\":\"2015-09-14T07:53:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7\"},\"description\":\"S\u00edmbolo del progreso y la modernidad, eje indiscutible de la zona financiera de la ciudad, el Paseo de la Castellana es una de las avenidas m\u00e1s importantes de Madrid.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Paseo de la Castellana antiguamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website\",\"url\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/\",\"name\":\"Blog, dulce blog\",\"description\":\"El blog inmobiliario de Estate One\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7\",\"name\":\"Estate One\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g\",\"caption\":\"Estate One\"},\"description\":\"Estate One somos una compa\u00f1\u00eda con un amplio conocimiento del mercado inmobiliario en Espa\u00f1a y una s\u00f3lida experiencia en prestigiosas empresas del sector.\",\"sameAs\":[\"http:\/\/estateone.biz\/\"],\"url\":\"https:\/\/www.estateone.biz\/blog\/author\/wpluzti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Paseo de la Castellana antiguamente - Blog, dulce blog","description":"S\u00edmbolo del progreso y la modernidad, eje indiscutible de la zona financiera de la ciudad, el Paseo de la Castellana es una de las avenidas m\u00e1s importantes de Madrid.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/","og_locale":"es_ES","og_type":"article","og_title":"El Paseo de la Castellana antiguamente - Blog, dulce blog","og_description":"S\u00edmbolo del progreso y la modernidad, eje indiscutible de la zona financiera de la ciudad, el Paseo de la Castellana es una de las avenidas m\u00e1s importantes de Madrid.","og_url":"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/","og_site_name":"Blog, dulce blog","article_published_time":"2015-09-14T07:34:39+00:00","article_modified_time":"2015-09-14T07:53:53+00:00","og_image":[{"width":650,"height":429,"url":"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2015\/09\/00-caste.jpg","type":"image\/jpeg"}],"author":"Estate One","twitter_card":"summary","twitter_misc":{"Escrito por":"Estate One","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/","url":"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/","name":"El Paseo de la Castellana antiguamente - Blog, dulce blog","isPartOf":{"@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website"},"datePublished":"2015-09-14T07:34:39+00:00","dateModified":"2015-09-14T07:53:53+00:00","author":{"@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7"},"description":"S\u00edmbolo del progreso y la modernidad, eje indiscutible de la zona financiera de la ciudad, el Paseo de la Castellana es una de las avenidas m\u00e1s importantes de Madrid.","breadcrumb":{"@id":"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estateone.biz\/blog\/el-paseo-de-la-castellana-antiguamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.estateone.biz\/blog\/?lang=en\/"},{"@type":"ListItem","position":2,"name":"El Paseo de la Castellana antiguamente"}]},{"@type":"WebSite","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website","url":"https:\/\/www.estateone.biz\/blog\/?lang=en\/","name":"Blog, dulce blog","description":"El blog inmobiliario de Estate One","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estateone.biz\/blog\/?lang=en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7","name":"Estate One","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g","caption":"Estate One"},"description":"Estate One somos una compa\u00f1\u00eda con un amplio conocimiento del mercado inmobiliario en Espa\u00f1a y una s\u00f3lida experiencia en prestigiosas empresas del sector.","sameAs":["http:\/\/estateone.biz\/"],"url":"https:\/\/www.estateone.biz\/blog\/author\/wpluzti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/1622"}],"collection":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":3,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"predecessor-version":[{"id":1651,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/1622\/revisions\/1651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/media\/1623"}],"wp:attachment":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/tags?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}