{"id":31678,"date":"2019-10-30T09:38:15","date_gmt":"2019-10-30T08:38:15","guid":{"rendered":"https:\/\/www.estateone.biz\/blog\/?p=31678"},"modified":"2019-10-30T09:38:17","modified_gmt":"2019-10-30T08:38:17","slug":"la-vivienda-de-alquiler-sigue-subiendo","status":"publish","type":"post","link":"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/","title":{"rendered":"La vivienda de alquiler sigue subiendo"},"content":{"rendered":"\n<p>La <strong>vivienda de alquiler sigue subiendo<\/strong>, y la <strong>Comunidad de Madrid est\u00e1 a la cabeza <\/strong>de esta subida de precios. Es la conclusi\u00f3n que puede extraerse del informe que hizo p\u00fablico recientemente Fomento basado en los <strong>dep\u00f3sitos de fianza<\/strong>, aunque hay que decir que en dicho informe s\u00f3lo se analizaron <strong>ocho comunidades aut\u00f3nomas<\/strong>. Las comunidades de las que se ofrecieron datos fueron Andaluc\u00eda, Arag\u00f3n, Baleares, Castilla y Le\u00f3n, Catalu\u00f1a, Comunidad Valenciana, Galicia y Madrid. <a rel=\"noreferrer noopener\" aria-label=\"Hace poco dec\u00edamos en este blog que la vivienda se modera y empieza a ralentizar sus precios (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.estateone.biz\/blog\/la-vivienda-se-modera\/ \" target=\"_blank\">Hace poco dec\u00edamos en este blog que <\/a><strong><a rel=\"noreferrer noopener\" aria-label=\"Hace poco dec\u00edamos en este blog que la vivienda se modera y empieza a ralentizar sus precios (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.estateone.biz\/blog\/la-vivienda-se-modera\/ \" target=\"_blank\">la vivienda se modera y empieza a ralentizar sus precios<\/a><\/strong>, si bien dicha moderaci\u00f3n se refiere a la compraventa, no al alquiler. Y es que <a rel=\"noreferrer noopener\" aria-label=\"hoy en d\u00eda comprar vivienda en Espa\u00f1a es m\u00e1s barato que alquilarla (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.estateone.biz\/blog\/comprar-vivienda-mas-barato-que-alquilarla\/\" target=\"_blank\">hoy en d\u00eda <\/a><strong><a rel=\"noreferrer noopener\" aria-label=\"hoy en d\u00eda comprar vivienda en Espa\u00f1a es m\u00e1s barato que alquilarla (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.estateone.biz\/blog\/comprar-vivienda-mas-barato-que-alquilarla\/\" target=\"_blank\">comprar vivienda en Espa\u00f1a es m\u00e1s barato que alquilarla<\/a><\/strong>, lo cual no sorprende demasiado si analizamos <strong>las subidas que se producen en el alquiler a\u00f1o tras a\u00f1o<\/strong>. Este \u00faltimo informe de Fomento, referido al pasado 2018, es clarificador, pues <strong>en todas las comunidades aut\u00f3nomas analizadas se produjo un incremento de precios<\/strong>. Ve\u00e1moslo m\u00e1s en detalle.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"650\" height=\"385\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/01-alquiler.jpg\" alt=\"La vivienda de alquiler sigue subiendo \" class=\"wp-image-31680\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/01-alquiler.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/01-alquiler-300x178.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<h2><strong>COMUNIDAD DE MADRID, A LA CABEZA<\/strong><\/h2>\n\n\n\n<p>En la <strong>Comunidad de Madrid<\/strong> el precio del <strong>alquiler subi\u00f3 por encima del 15%<\/strong> en 2018 respecto a 2017. La cifra habla por s\u00ed sola (si nos fijamos en el <strong>m2,<\/strong> la subida es de <strong>10,7\u20ac<\/strong>) y permite hacerse una idea de c\u00f3mo se ha encarecido en un a\u00f1o el alquiler de vivienda en la capital. En <strong>Catalu\u00f1a<\/strong> esta subida fue mucho menos acusada (un <strong>6,7%<\/strong>, unos <strong>8,7\u20ac por m2<\/strong>). Del resto de comunidades analizadas por Fomento, <strong>Baleares<\/strong> se sit\u00faa muy cerca de Madrid, con una <strong>subida del 14,9%<\/strong> (<strong>7,9\u20ac por m2<\/strong>). Le siguen <strong>Arag\u00f3n<\/strong> con un <strong>11,7%<\/strong> (<strong>5,8\u20ac por m2<\/strong>) y <strong>Comunidad Valenciana<\/strong> (<strong>10,2%<\/strong> de subida, <strong>5,4\u20ac por m2<\/strong>). Por detr\u00e1s de Catalu\u00f1a quedan <strong>Castilla y Le\u00f3n<\/strong> (<strong>4,5%<\/strong> de subida, <strong>4,7\u20ac por m2<\/strong>) y <strong>Galicia<\/strong> (<strong>4,2%<\/strong> de subida, <strong>4,7\u20ac por m2<\/strong>). Atendiendo a <strong>la renta del alquiler<\/strong>, tambi\u00e9n la <strong>Comunidad de Madrid<\/strong> est\u00e1 a la cabeza, con <strong>una renta media que supera los 800\u20ac en un inmueble con menos de 90 m2<\/strong> (concretamente se calcula una <strong>renta media de 819\u20ac<\/strong> en una propiedad de <strong>86 m2<\/strong>). No es de extra\u00f1ar que con unos precios del alquiler tan al alza, <strong>la compra de vivienda sea una opci\u00f3n cada vez m\u00e1s considerada<\/strong> por muchas familias. A Madrid le sigue <strong>Catalu\u00f1a<\/strong> (<strong>693\u20ac<\/strong> de media en un inmueble de <strong>98 m2<\/strong>), <strong>Baleares<\/strong> (<strong>687\u20ac<\/strong> en un inmueble de <strong>100 m2<\/strong>), <strong>Comunidad Valenciana <\/strong>(<strong>535\u20ac<\/strong> en <strong>105 m2<\/strong>), <strong>Andaluc\u00eda<\/strong> (<strong>503\u20ac<\/strong> en <strong>97 m2<\/strong>), <strong>Arag\u00f3n<\/strong> (<strong>453\u20ac <\/strong>en <strong>83 m2<\/strong>), <strong>Castilla y Le\u00f3n<\/strong> (<strong>429\u20ac <\/strong>en <strong>99 m2<\/strong>) y <strong>Galicia<\/strong> (<strong>418\u20ac<\/strong> en <strong>99 m2<\/strong>).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"650\" height=\"452\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/02-alquiler.jpg\" alt=\"La vivienda de alquiler sigue subiendo \" class=\"wp-image-31681\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/02-alquiler.jpg 650w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/02-alquiler-300x209.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<h2><strong>SAN SEBASTI\u00c1N, LA CIUDAD M\u00c1S CARA<\/strong><\/h2>\n\n\n\n<p>Si nos detenemos en nuestras ciudades principales, <strong>San Sebasti\u00e1n es la que mayor renta alcanza<\/strong>. En la capital guipuzcoana la subida se sit\u00faa en <strong>14\u20ac por m2<\/strong>. Le sigue <strong>Barcelona con 12,5\u20ac por m2<\/strong>, <strong>Madrid<\/strong> (<strong>12\u20ac por m2<\/strong>) e <strong>Ibiza<\/strong> (<strong>11,8\u20ac por m2<\/strong>). Si tenemos en cuenta la superficie de los inmuebles que se alquilan, la localidad m\u00e1s cara para vivir de alquiler en Espa\u00f1a ser\u00eda <strong>Boadilla del Monte<\/strong> (con un precio de <strong>1.200\u20ac al mes<\/strong>), seguida de <strong>Pozuelo de Alarc\u00f3n<\/strong> (<strong>1.173\u20ac al mes<\/strong>) y <strong>Sant Cugat del Vall\u00e9s<\/strong> (<strong>1.150\u20ac al mes<\/strong>). \u00bfEst\u00e1 el alquiler llegando a su techo de precios en nuestro pa\u00eds, o todav\u00eda se encarecer\u00e1 m\u00e1s? Estaremos atentos al mercado para saberlo.<\/p>\n\n\n\n<p><strong>Fotograf\u00eda 02:<\/strong> Zarateman <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vivienda de alquiler sigue subiendo, y la Comunidad de Madrid est\u00e1 a la cabeza de esta subida de precios. Es la conclusi\u00f3n que puede extraerse del informe que hizo p\u00fablico recientemente Fomento basado en los dep\u00f3sitos de fianza, aunque hay que decir que en dicho informe s\u00f3lo se analizaron ocho comunidades aut\u00f3nomas. Las comunidades &hellip;<\/p>\n","protected":false},"author":1,"featured_media":31679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[21,74,172],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La vivienda de alquiler sigue subiendo - Blog, dulce blog<\/title>\n<meta name=\"description\" content=\"La vivienda de alquiler sigue subiendo, y la Comunidad de Madrid est\u00e1 a la cabeza de esta subida de precios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vivienda de alquiler sigue subiendo - Blog, dulce blog\" \/>\n<meta property=\"og:description\" content=\"La vivienda de alquiler sigue subiendo, y la Comunidad de Madrid est\u00e1 a la cabeza de esta subida de precios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog, dulce blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-30T08:38:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-30T08:38:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/00-alquiler.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Estate One\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estate One\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/\",\"url\":\"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/\",\"name\":\"La vivienda de alquiler sigue subiendo - Blog, dulce blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website\"},\"datePublished\":\"2019-10-30T08:38:15+00:00\",\"dateModified\":\"2019-10-30T08:38:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7\"},\"description\":\"La vivienda de alquiler sigue subiendo, y la Comunidad de Madrid est\u00e1 a la cabeza de esta subida de precios.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vivienda de alquiler sigue subiendo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website\",\"url\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/\",\"name\":\"Blog, dulce blog\",\"description\":\"El blog inmobiliario de Estate One\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7\",\"name\":\"Estate One\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g\",\"caption\":\"Estate One\"},\"description\":\"Estate One somos una compa\u00f1\u00eda con un amplio conocimiento del mercado inmobiliario en Espa\u00f1a y una s\u00f3lida experiencia en prestigiosas empresas del sector.\",\"sameAs\":[\"http:\/\/estateone.biz\/\"],\"url\":\"https:\/\/www.estateone.biz\/blog\/author\/wpluzti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vivienda de alquiler sigue subiendo - Blog, dulce blog","description":"La vivienda de alquiler sigue subiendo, y la Comunidad de Madrid est\u00e1 a la cabeza de esta subida de precios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/","og_locale":"es_ES","og_type":"article","og_title":"La vivienda de alquiler sigue subiendo - Blog, dulce blog","og_description":"La vivienda de alquiler sigue subiendo, y la Comunidad de Madrid est\u00e1 a la cabeza de esta subida de precios.","og_url":"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/","og_site_name":"Blog, dulce blog","article_published_time":"2019-10-30T08:38:15+00:00","article_modified_time":"2019-10-30T08:38:17+00:00","og_image":[{"width":650,"height":367,"url":"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2019\/10\/00-alquiler.jpg","type":"image\/jpeg"}],"author":"Estate One","twitter_card":"summary","twitter_misc":{"Escrito por":"Estate One","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/","url":"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/","name":"La vivienda de alquiler sigue subiendo - Blog, dulce blog","isPartOf":{"@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website"},"datePublished":"2019-10-30T08:38:15+00:00","dateModified":"2019-10-30T08:38:17+00:00","author":{"@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7"},"description":"La vivienda de alquiler sigue subiendo, y la Comunidad de Madrid est\u00e1 a la cabeza de esta subida de precios.","breadcrumb":{"@id":"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estateone.biz\/blog\/la-vivienda-de-alquiler-sigue-subiendo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.estateone.biz\/blog\/?lang=en\/"},{"@type":"ListItem","position":2,"name":"La vivienda de alquiler sigue subiendo"}]},{"@type":"WebSite","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website","url":"https:\/\/www.estateone.biz\/blog\/?lang=en\/","name":"Blog, dulce blog","description":"El blog inmobiliario de Estate One","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estateone.biz\/blog\/?lang=en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7","name":"Estate One","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g","caption":"Estate One"},"description":"Estate One somos una compa\u00f1\u00eda con un amplio conocimiento del mercado inmobiliario en Espa\u00f1a y una s\u00f3lida experiencia en prestigiosas empresas del sector.","sameAs":["http:\/\/estateone.biz\/"],"url":"https:\/\/www.estateone.biz\/blog\/author\/wpluzti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/31678"}],"collection":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/comments?post=31678"}],"version-history":[{"count":1,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/31678\/revisions"}],"predecessor-version":[{"id":31682,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/31678\/revisions\/31682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/media\/31679"}],"wp:attachment":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/media?parent=31678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/categories?post=31678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/tags?post=31678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}