{"id":35375,"date":"2024-11-27T12:10:45","date_gmt":"2024-11-27T11:10:45","guid":{"rendered":"https:\/\/www.estateone.biz\/blog\/?p=35375"},"modified":"2024-11-27T12:13:15","modified_gmt":"2024-11-27T11:13:15","slug":"paseando-por-la-plaza-del-cordon","status":"publish","type":"post","link":"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/","title":{"rendered":"Paseando por la plaza del Cord\u00f3n"},"content":{"rendered":"\n<p>La <strong>Plaza del Cord\u00f3n<\/strong> es una <strong>peque\u00f1a plaza del barrio de Palacio<\/strong>, en pleno coraz\u00f3n del <strong><a href=\"https:\/\/www.estateone.biz\/blog\/recorriendo-el-madrid-de-los-austrias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Madrid de los Austrias<\/a><\/strong>. Se trata de una <strong>plaza hist\u00f3rica<\/strong> enclavada en el centro de Madrid, <strong>cuyos or\u00edgenes se remontan al S. XVI<\/strong>. Como otras plazas del casco viejo madrile\u00f1o, en ella <strong>destaca su trazado medieval<\/strong>, as\u00ed como <strong>su mezcla de estilos arquitect\u00f3nicos de los siglos XVII y XVIII<\/strong>. En esta plaza <strong>desembocan cuatro calles<\/strong>: la calle del Cord\u00f3n, <a href=\"https:\/\/www.estateone.biz\/blog\/tag\/calle-del-sacramento\/\" target=\"_blank\" rel=\"noreferrer noopener\">la calle del Sacramento<\/a>, la calle de San Justo y la de Doctor Letamendi. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"750\" height=\"563\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/01-cordon.jpg\" alt=\"Plaza del Cord\u00f3n\" class=\"wp-image-35376\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/01-cordon.jpg 750w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/01-cordon-300x225.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption>La Plaza del Cord\u00f3n, con la Bas\u00edlica de San Miguel a la derecha<\/figcaption><\/figure>\n\n\n\n<p>Una curiosidad de la <strong>calle del Cord\u00f3n<\/strong> es que <strong>hasta el a\u00f1o 1835 se la conoc\u00eda como <em>Calle de los Azotados<\/em><\/strong>, pues por ella pasaban los condenados a recibir azotes que sal\u00edan de la antigua C\u00e1rcel de la Villa. Este nombre tambi\u00e9n se emple\u00f3 alg\u00fan tiempo para la plaza, siendo conocida como <strong><em>Plaza de los Azotados<\/em><\/strong>. En nuestros d\u00edas,<strong> dar un paseo por el Madrid antiguo y terminarlo en la Plaza del Cord\u00f3n<\/strong> es una experiencia m\u00e1s que reconfortante, pues nos sirve para <strong>recuperar la esencia de lo que fue esta ciudad en otras \u00e9pocas<\/strong>, recordar c\u00f3mo eran entonces sus calles y sus plazas, e <strong>imaginar cu\u00e1l era el pulso de la ciudad hace siglos<\/strong>. <a href=\"https:\/\/www.estateone.biz\/blog\/plaza-de-la-villa-corazon-del-madrid-medieval\/\" target=\"_blank\" rel=\"noreferrer noopener\">La \u00faltima vez que estuvimos en nuestra secci\u00f3n <strong>Lugares con mucha Historia<\/strong> fue para <strong>conocer<\/strong> <strong>la Plaza de la Villa<\/strong><\/a>; hoy nos vamos a escasos metros de all\u00ed para visitar otra plaza imprescindible del casco hist\u00f3rico madrile\u00f1o: la <strong>Plaza del Cord\u00f3n<\/strong>. Te invitamos a que nos sigas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"750\" height=\"563\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/02-cordon.jpg\" alt=\"Paseando por la plaza del Cord\u00f3n\" class=\"wp-image-35377\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/02-cordon.jpg 750w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/02-cordon-300x225.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption>Los or\u00edgenes de la Plaza del Cord\u00f3n se remontan al siglo XVI<\/figcaption><\/figure>\n\n\n\n<h2><strong>UNA PLAZA CON SOLERA Y UN PALACIO<\/strong><\/h2>\n\n\n\n<p>La <strong>primera referencia<\/strong> que encontramos de la <strong>Plaza del Cord\u00f3n<\/strong> est\u00e1 en el <strong>plano de Texeira, de 1656<\/strong> (nombrada en \u00e9l como <strong><em>Plazuela del Cord\u00f3n<\/em><\/strong>). En el siglo XIX la plaza se ubicaba en el antiguo <strong>barrio de Puerta Cerrada<\/strong>, tal y como puede verse en la <strong><em>Gu\u00eda de Madrid<\/em><\/strong> <strong>de 1876<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"750\" height=\"750\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/03-cordon.jpg\" alt=\"Paseando por la plaza del Cord\u00f3n\" class=\"wp-image-35378\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/03-cordon.jpg 750w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/03-cordon-300x300.jpg 300w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/03-cordon-150x150.jpg 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption>La Plaza del Cord\u00f3n en el plano de Teixeira de 1665<\/figcaption><\/figure>\n\n\n\n<p>Un edificio singular que hay en la plaza es el <strong>Palacio del Cord\u00f3n<\/strong>, ubicado <strong>en el n\u00famero 1<\/strong>: es un <strong>edificio barroco del siglo XVII <\/strong>construido <strong>a dos alturas<\/strong> en el que destacan <strong>dos cordones de piedra que se sit\u00faan a los lados de fachada<\/strong>. Pol\u00edticos como <strong>Manuel Becerra o Alberto Aguilera<\/strong> ten\u00edan su residencia all\u00ed. El Palacio del Cord\u00f3n no debe confundirse con las Casas del Cord\u00f3n, antiguas residencias que se ubicaban enfrente del palacio y que hoy en d\u00eda est\u00e1n desaparecidas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"658\" height=\"1024\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/04-cordon-658x1024.jpg\" alt=\"Paseando por la plaza del Cord\u00f3n\" class=\"wp-image-35379\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/04-cordon-658x1024.jpg 658w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/04-cordon-193x300.jpg 193w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/04-cordon.jpg 750w\" sizes=\"(max-width: 658px) 100vw, 658px\" \/><figcaption>Azulejos de la Plaza del Cord\u00f3n<\/figcaption><\/figure>\n\n\n\n<h2><strong>UN LUGAR TRANQUILO, COMO YA DEC\u00cdAN LAS CR\u00d3NICAS<\/strong><\/h2>\n\n\n\n<p>La <strong>Plaza del Cord\u00f3n<\/strong> destaca por su apacibilidad; es una <strong>plaza peque\u00f1a y tranquila que invita al recogimiento para<\/strong> <strong>disfrutarla con calma<\/strong> y desconectar del estr\u00e9s de la gran ciudad. Esto ya lo dec\u00eda <strong>el cronista madrile\u00f1o Pedro de R\u00e9pide<\/strong>, que lleg\u00f3 a describir la plaza como <strong><em>un paraje venerable y apacible<\/em><\/strong>. De la plaza, <strong>el cronista destacaba su privilegiado entorno<\/strong>, con las cercanas <strong>Casa de Cisneros<\/strong> y la <strong>antigua Iglesia de San Justo y San Pastor<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"750\" height=\"500\" src=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/05-cordon.jpg\" alt=\"Paseando por la plaza del Cord\u00f3n\" class=\"wp-image-35380\" srcset=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/05-cordon.jpg 750w, https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/05-cordon-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption>Se trata de una plaza peque\u00f1a y tranquila que invita al recogimiento para disfrutarla con calma<\/figcaption><\/figure>\n\n\n\n<h2><strong>\u00bfSAB\u00cdAS QU\u00c9\u2026?<\/strong><\/h2>\n\n\n\n<p>Al lado de la Plaza del Cord\u00f3n se ubicaba antiguamente el <strong>Palacio de Iv\u00e1n de Vargas<\/strong> (hoy desaparecido), donde se dec\u00eda que lleg\u00f3 a residir San Isidro, actual patr\u00f3n de Madrid. Hoy en d\u00eda el espacio de este antiguo palacio lo ocupa la <strong>Biblioteca Iv\u00e1n de Vargas<\/strong>.<\/p>\n\n\n\n<p><strong>Fotograf\u00eda 01:<\/strong> Bernard Gagnon<\/p>\n\n\n\n<p><strong>Fotograf\u00eda 02:<\/strong> <a href=\"https:\/\/www.flickr.com\/photos\/savingfutures\/\" target=\"_blank\" rel=\"noreferrer noopener\">Charlie Phillips<\/a> <\/p>\n\n\n\n<p><strong>Fotograf\u00eda 04:<\/strong> Pedro Reina<\/p>\n\n\n\n<p><strong>Fotograf\u00eda 05:<\/strong> <a href=\"https:\/\/www.flickr.com\/photos\/129231073@N06\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fred Romero<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Plaza del Cord\u00f3n es una peque\u00f1a plaza del barrio de Palacio, en pleno coraz\u00f3n del Madrid de los Austrias. Se trata de una plaza hist\u00f3rica enclavada en el centro de Madrid, cuyos or\u00edgenes se remontan al S. XVI. Como otras plazas del casco viejo madrile\u00f1o, en ella destaca su trazado medieval, as\u00ed como su &hellip;<\/p>\n","protected":false},"author":1,"featured_media":35381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[132],"tags":[25,26,237,1271,1880],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paseando por la plaza del Cord\u00f3n - Blog, dulce blog<\/title>\n<meta name=\"description\" content=\"La Plaza del Cord\u00f3n es una peque\u00f1a plaza del barrio de Palacio, en pleno coraz\u00f3n del Madrid de los Austrias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paseando por la plaza del Cord\u00f3n - Blog, dulce blog\" \/>\n<meta property=\"og:description\" content=\"La Plaza del Cord\u00f3n es una peque\u00f1a plaza del barrio de Palacio, en pleno coraz\u00f3n del Madrid de los Austrias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog, dulce blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T11:10:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T11:13:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/00-pzacordon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Estate One\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estate One\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/\",\"url\":\"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/\",\"name\":\"Paseando por la plaza del Cord\u00f3n - Blog, dulce blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website\"},\"datePublished\":\"2024-11-27T11:10:45+00:00\",\"dateModified\":\"2024-11-27T11:13:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7\"},\"description\":\"La Plaza del Cord\u00f3n es una peque\u00f1a plaza del barrio de Palacio, en pleno coraz\u00f3n del Madrid de los Austrias\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paseando por la plaza del Cord\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website\",\"url\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/\",\"name\":\"Blog, dulce blog\",\"description\":\"El blog inmobiliario de Estate One\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7\",\"name\":\"Estate One\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g\",\"caption\":\"Estate One\"},\"description\":\"Estate One somos una compa\u00f1\u00eda con un amplio conocimiento del mercado inmobiliario en Espa\u00f1a y una s\u00f3lida experiencia en prestigiosas empresas del sector.\",\"sameAs\":[\"http:\/\/estateone.biz\/\"],\"url\":\"https:\/\/www.estateone.biz\/blog\/author\/wpluzti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paseando por la plaza del Cord\u00f3n - Blog, dulce blog","description":"La Plaza del Cord\u00f3n es una peque\u00f1a plaza del barrio de Palacio, en pleno coraz\u00f3n del Madrid de los Austrias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/","og_locale":"es_ES","og_type":"article","og_title":"Paseando por la plaza del Cord\u00f3n - Blog, dulce blog","og_description":"La Plaza del Cord\u00f3n es una peque\u00f1a plaza del barrio de Palacio, en pleno coraz\u00f3n del Madrid de los Austrias","og_url":"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/","og_site_name":"Blog, dulce blog","article_published_time":"2024-11-27T11:10:45+00:00","article_modified_time":"2024-11-27T11:13:15+00:00","og_image":[{"width":650,"height":440,"url":"https:\/\/www.estateone.biz\/blog\/wp-content\/uploads\/2024\/11\/00-pzacordon.jpg","type":"image\/jpeg"}],"author":"Estate One","twitter_card":"summary","twitter_misc":{"Escrito por":"Estate One","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/","url":"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/","name":"Paseando por la plaza del Cord\u00f3n - Blog, dulce blog","isPartOf":{"@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website"},"datePublished":"2024-11-27T11:10:45+00:00","dateModified":"2024-11-27T11:13:15+00:00","author":{"@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7"},"description":"La Plaza del Cord\u00f3n es una peque\u00f1a plaza del barrio de Palacio, en pleno coraz\u00f3n del Madrid de los Austrias","breadcrumb":{"@id":"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estateone.biz\/blog\/paseando-por-la-plaza-del-cordon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.estateone.biz\/blog\/?lang=en\/"},{"@type":"ListItem","position":2,"name":"Paseando por la plaza del Cord\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#website","url":"https:\/\/www.estateone.biz\/blog\/?lang=en\/","name":"Blog, dulce blog","description":"El blog inmobiliario de Estate One","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estateone.biz\/blog\/?lang=en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/5c4d73bb88472ee2f9325e6ce4f634d7","name":"Estate One","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.estateone.biz\/blog\/?lang=en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b36ec0d2dc5448ccdc0852ddf52cf7a4?s=96&d=identicon&r=g","caption":"Estate One"},"description":"Estate One somos una compa\u00f1\u00eda con un amplio conocimiento del mercado inmobiliario en Espa\u00f1a y una s\u00f3lida experiencia en prestigiosas empresas del sector.","sameAs":["http:\/\/estateone.biz\/"],"url":"https:\/\/www.estateone.biz\/blog\/author\/wpluzti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/35375"}],"collection":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/comments?post=35375"}],"version-history":[{"count":1,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/35375\/revisions"}],"predecessor-version":[{"id":35382,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/posts\/35375\/revisions\/35382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/media\/35381"}],"wp:attachment":[{"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/media?parent=35375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/categories?post=35375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estateone.biz\/blog\/wp-json\/wp\/v2\/tags?post=35375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}